{"id":12932,"date":"2024-07-09T00:40:00","date_gmt":"2024-07-09T04:40:00","guid":{"rendered":"https:\/\/monastere.ca\/?post_type=pensions&#038;p=12932"},"modified":"2026-03-09T11:15:39","modified_gmt":"2026-03-09T15:15:39","slug":"retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026","status":"publish","type":"pensions","link":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/","title":{"rendered":"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","pension-tag":[],"class_list":["post-12932","pensions","type-pensions","status-publish","hentry","pension_organizer-jeanne-dube-blanchet","pension_organizer-marjorie-ouellet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines<\/title>\n<meta name=\"description\" content=\"Un s\u00e9jour unique rempli de bien-\u00eatre et d&#039;activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines\" \/>\n<meta property=\"og:description\" content=\"Un s\u00e9jour unique rempli de bien-\u00eatre et d&#039;activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Monast\u00e8re des Augustines\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/monastere.ca\/?locale=fr_CA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T15:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monastere.ca\/wp-content\/uploads\/2023\/08\/Image_OG_1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/retreat\\\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\\\/\",\"url\":\"https:\\\/\\\/monastere.ca\\\/en\\\/retreat\\\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\\\/\",\"name\":\"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#website\"},\"datePublished\":\"2024-07-09T04:40:00+00:00\",\"dateModified\":\"2026-03-09T15:15:39+00:00\",\"description\":\"Un s\u00e9jour unique rempli de bien-\u00eatre et d'activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/retreat\\\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monastere.ca\\\/en\\\/retreat\\\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/retreat\\\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/monastere.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/monastere.ca\\\/en\\\/\",\"name\":\"Monast\u00e8re des Augustines\",\"description\":\"Monast\u00e8re des Augustines, un havre patrimonial authentique de sant\u00e9 et de mieux-\u00eatre avec atelier, spa, mus\u00e9e, restaurant et h\u00f4tellerie au Qu\u00e9bec.\",\"publisher\":{\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monastere.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#organization\",\"name\":\"Monast\u00e8re des Augustines\",\"url\":\"https:\\\/\\\/monastere.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/monastere.ca\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-monastere.svg\",\"contentUrl\":\"https:\\\/\\\/monastere.ca\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-monastere.svg\",\"width\":1,\"height\":1,\"caption\":\"Monast\u00e8re des Augustines\"},\"image\":{\"@id\":\"https:\\\/\\\/monastere.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/monastere.ca\\\/?locale=fr_CA\",\"https:\\\/\\\/www.instagram.com\\\/lemonasteredesaugustines\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-monastere-des-augustines\\\/?originalSubdomain=ca\",\"https:\\\/\\\/fr.tripadvisor.ca\\\/Hotel_Review-g155033-d8460643-Reviews-Le_Monastere_des_Augustines-Quebec_City_Quebec.html\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines","description":"Un s\u00e9jour unique rempli de bien-\u00eatre et d'activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/","og_locale":"en_US","og_type":"article","og_title":"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines","og_description":"Un s\u00e9jour unique rempli de bien-\u00eatre et d'activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.","og_url":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/","og_site_name":"Monast\u00e8re des Augustines","article_publisher":"https:\/\/www.facebook.com\/monastere.ca\/?locale=fr_CA","article_modified_time":"2026-03-09T15:15:39+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/monastere.ca\/wp-content\/uploads\/2023\/08\/Image_OG_1200x675.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/","url":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/","name":"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat - Monast\u00e8re des Augustines","isPartOf":{"@id":"https:\/\/monastere.ca\/en\/#website"},"datePublished":"2024-07-09T04:40:00+00:00","dateModified":"2026-03-09T15:15:39+00:00","description":"Un s\u00e9jour unique rempli de bien-\u00eatre et d'activit\u00e9s stimulantes telles que du yoga fitness et une exp\u00e9rience thermale Str\u00f8m spa nordique Vieux-Qu\u00e9bec.","breadcrumb":{"@id":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/monastere.ca\/en\/retreat\/retraite-fitness-bien-etre-et-experience-thermale-wetreat-mars-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/monastere.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Yoga fitness bien-\u00eatre et exp\u00e9rience thermale avec wetreat"}]},{"@type":"WebSite","@id":"https:\/\/monastere.ca\/en\/#website","url":"https:\/\/monastere.ca\/en\/","name":"Monast\u00e8re des Augustines","description":"Monast\u00e8re des Augustines, un havre patrimonial authentique de sant\u00e9 et de mieux-\u00eatre avec atelier, spa, mus\u00e9e, restaurant et h\u00f4tellerie au Qu\u00e9bec.","publisher":{"@id":"https:\/\/monastere.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monastere.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/monastere.ca\/en\/#organization","name":"Monast\u00e8re des Augustines","url":"https:\/\/monastere.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/monastere.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/monastere.ca\/wp-content\/uploads\/2023\/07\/logo-monastere.svg","contentUrl":"https:\/\/monastere.ca\/wp-content\/uploads\/2023\/07\/logo-monastere.svg","width":1,"height":1,"caption":"Monast\u00e8re des Augustines"},"image":{"@id":"https:\/\/monastere.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/monastere.ca\/?locale=fr_CA","https:\/\/www.instagram.com\/lemonasteredesaugustines\/","https:\/\/www.linkedin.com\/company\/le-monastere-des-augustines\/?originalSubdomain=ca","https:\/\/fr.tripadvisor.ca\/Hotel_Review-g155033-d8460643-Reviews-Le_Monastere_des_Augustines-Quebec_City_Quebec.html"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/monastere.ca\/en\/wp-json\/wp\/v2\/pensions\/12932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monastere.ca\/en\/wp-json\/wp\/v2\/pensions"}],"about":[{"href":"https:\/\/monastere.ca\/en\/wp-json\/wp\/v2\/types\/pensions"}],"wp:attachment":[{"href":"https:\/\/monastere.ca\/en\/wp-json\/wp\/v2\/media?parent=12932"}],"wp:term":[{"taxonomy":"pension-tag","embeddable":true,"href":"https:\/\/monastere.ca\/en\/wp-json\/wp\/v2\/pension-tag?post=12932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}